{"id":270,"date":"2021-04-27T17:09:57","date_gmt":"2021-04-27T17:09:57","guid":{"rendered":"https:\/\/lsmfa.bluezone.mx\/?p=270"},"modified":"2021-05-16T17:01:09","modified_gmt":"2021-05-16T17:01:09","slug":"falcon-soldado-invierno","status":"publish","type":"post","link":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/","title":{"rendered":"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><span class=\"has-inline-color has-vivid-red-color\">ALERTA: CONTIENE SPOILERS<\/span><\/strong><\/p>\n\n\n\n<p>Despu\u00e9s de la serie emocionante, enigm\u00e1tica y un tanto rom\u00e1ntica de WandaVision, muchos de nosotros nos quedamos con un buen sabor de boca, con la emoci\u00f3n que Marvel iba a sacar series con excelente calidad igualando la s\u00faper pareja. \u00bfSer\u00edan Sam Wilson y Bucky Barnes la nueva dupla her\u00f3ica que me har\u00eda levantarme de la cama con un brinco de felicidad viernes por la ma\u00f1ana, luego dej\u00e1ndome en el borde de mi asiento con un dolor de pecho por saber qu\u00e9 suceder\u00e1 la pr\u00f3xima semana? Por ahora, no ha sido as\u00ed.<\/p>\n\n\n\n<p>Aunque ni Falcon ni Bucky han formado parte de mis personajes favoritos en el MCU, puedo decir que he visto suficientes series de d\u00faos con una relaci\u00f3n amor odio para esperar a <em>Falcon y el Soldado del Invierno<\/em> con singular alegr\u00eda, viendo c\u00f3mo se desarrollaba su din\u00e1mica. Algo as\u00ed como Sherlock Holmes y John Watson en la serie<br>con Benedict Cumberbatch, Arziraphale y Crowley en la serie <em>Good Omens<\/em>, o incluso Chloe Decker y el mism\u00edsimo diablo en la serie <em>Lucifer<\/em>; en donde dos opuestos, aunque chocantes, terminan teniendo sed de aventurarse de lado a lado, as\u00ed desenvolviendo una relaci\u00f3n interesante.<\/p>\n\n\n\n<p>Para mi sorpresa, al final no se trat\u00f3 del d\u00fao de superh\u00e9roes, sino de una serie de problemas detr\u00e1s de la creaci\u00f3n gubernamental del suero que le dio el poder de Capit\u00e1n Am\u00e9rica a Steve Rogers. Y pues, no qued\u00e9 satisfecha\u2026<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/fws1-1024x683.jpeg\" alt=\"\" class=\"wp-image-271\" srcset=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/fws1-1024x683.jpeg 1024w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/fws1-300x200.jpeg 300w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/fws1-768x512.jpeg 768w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/fws1-1536x1024.jpeg 1536w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/fws1.jpeg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>The Falcon and The Winter Soldier. \u00a9Marvel Studios 2021.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Quiz\u00e1 sea un poco m\u00e1s desarrollada en la siguiente temporada, pero para una serie que tiene en el t\u00edtulo el conjunto de dos h\u00e9roes, que en la pantalla los mostraba trabajando juntos; al final fueron dos mentes en sus propios caminos, no siendo suficientes para ning\u00fan desarrollo de sus personajes, ni de su relaci\u00f3n, dej\u00e1ndome aburrida en varios episodios.<\/p>\n\n\n\n<p>La historia, por una parte, comienza con la familia de Sam queriendo reparar el barco de sus padres junto a su hermana y sus hijos, mientras discierne si deber\u00eda de tomar el rol de cap despu\u00e9s de que el antiguo Capit\u00e1n Am\u00e9rica cedi\u00f3 el cargo. Para mi gusto, estos dos factores no ten\u00edan conexi\u00f3n en lo absoluto entre s\u00ed, ni profundizaci\u00f3n. La serie no se esmer\u00f3 para que me importaran sus sobrinos ni hermana, tampoco se me hizo lindo que en alg\u00fan momento de la serie Bucky coqueteara con ella.<\/p>\n\n\n\n<p>Como tropo recurrente de varias series existentes hoy en d\u00eda, igualmente vemos a Sam tratando de hablar con los antagonistas de la serie y razonar con ellos. Se intent\u00f3 eliminar el sentimiento de clich\u00e9, agregando que el militante hab\u00eda trabajado con j\u00f3venes de la armada estadounidense y ten\u00eda mucha experiencia en el cargo; cosa que no fue conmocionante ver y hubiera sido fascinante ver alg\u00fan flashback para tener una referencia al gran <em>punch<\/em> que merec\u00edan esas escenas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/tag-103-21264_r-1024x683.jpeg\" alt=\"\" class=\"wp-image-272\" srcset=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/tag-103-21264_r-1024x683.jpeg 1024w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/tag-103-21264_r-300x200.jpeg 300w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/tag-103-21264_r-768x512.jpeg 768w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/tag-103-21264_r-1536x1024.jpeg 1536w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/tag-103-21264_r-2048x1365.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>The Falcon and The Winter Soldier. \u00a9Marvel Studios 2021.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Otro tropo que no tuvo la complejidad que se merec\u00eda, fue cuando se descubri\u00f3 el terrible secreto del sistema en el que tanto conf\u00eda Sam y el discernimiento fuerte que viene despu\u00e9s de eso. No se mostr\u00f3 el proceso del duelo que debi\u00f3 haber venido con el shock que trajo el que se desmoronan los pilares de principios y valores en los que estaba parado. Sam s\u00f3lo pasa por un peque\u00f1o enojo y prosigue a la aceptaci\u00f3n r\u00e1pida de esos nuevos descubrimientos que hizo durante el show.<\/p>\n\n\n\n<p>En resumidas cuentas, sigue siendo el personaje bidimensional que hemos visto en todo el MCU.<\/p>\n\n\n\n<p>Por otro lado, vemos la historia de redenci\u00f3n de Bucky, tomando el camino del perd\u00f3n y volviendo a vivir como un ser humano dejando atr\u00e1s el malvado asesino que alguna vez fue, de nombre \u2018\u2019El Soldado del invierno\u2019\u2019. Aunque, si has seguido a Capit\u00e1n Am\u00e9rica en las pel\u00edculas y bien sabes los momentos duros por las que pas\u00f3 este<br>personaje, la serie no te hace conocerlo m\u00e1s all\u00e1 de lo que ya se ha visto en pantalla; no te emociona verlo aparecer en el primer episodio intentando vivir una vida normal, no sientes empat\u00eda ante la culpa que le engulle el coraz\u00f3n por haber matado al hijo de uno de sus vecinos cuando fue aquel asesino despiadado, no te enloquece que se reencontrara a las dora milaje de Wakanda, ni a\u00fan cuando sabes que ellas fueron las que lo ayudaron descodificar su mente manipulada que hac\u00eda que fuera cruel en sus matanzas. Bucky sigue siendo un enigma para la audiencia.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/l-intro-1600199250-1024x575.jpeg\" alt=\"\" class=\"wp-image-273\" srcset=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/l-intro-1600199250-1024x575.jpeg 1024w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/l-intro-1600199250-300x169.jpeg 300w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/l-intro-1600199250-768x432.jpeg 768w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/l-intro-1600199250-1536x863.jpeg 1536w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/l-intro-1600199250.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>The Falcon and The Winter Soldier. \u00a9Marvel Studios 2021.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Ya que estaban trabajando juntos, buscando erradicar los varios peligros de la organizaci\u00f3n de los Flag Smashers (organizaci\u00f3n antinacionalista que busca erradicar las fronteras), que, aunque se mostr\u00f3 compleja, que ven\u00eda de buena fe y con mucho apoyo mundialmente, ni el objetivo de este fue comprensible. Igualmente, al final, apagando la flama del movimiento en el \u00faltimo episodio innecesariamente r\u00e1pido.<\/p>\n\n\n\n<p>Aun as\u00ed, tuve mis personajes favoritos (y no tan favoritos, pero reconozco que buenos) de la serie.<\/p>\n\n\n\n<p>Zemo, el villano de <em>Capit\u00e1n Am\u00e9rica: Civil War<\/em>, se convirti\u00f3 del t\u00edpico malvado, sediento de venganza porque su familia fue asesinada (realmente un villano olvidable), a un antih\u00e9roe multifac\u00e9tico, exc\u00e9ntrico y divertido (casi al nivel de Loki, dir\u00eda yo), gan\u00e1ndose, con toda raz\u00f3n, el coraz\u00f3n de todo el internet y entristeci\u00e9ndome el momento que sabr\u00eda que no aparecer\u00eda en el \u00faltimo episodio de la temporada.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/Zemo_Mask-1024x576.jpeg\" alt=\"\" class=\"wp-image-274\" srcset=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/Zemo_Mask-1024x576.jpeg 1024w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/Zemo_Mask-300x169.jpeg 300w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/Zemo_Mask-768x432.jpeg 768w, https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/Zemo_Mask.jpeg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>The Falcon and The Winter Soldier. \u00a9Marvel Studios 2021.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Karli Morgenthau, la villana de la serie, y los ojos de una ni\u00f1a inocente apag\u00e1ndose poco a poco, convirti\u00e9ndose en esos de una villana. Si bien el movimiento que encabezaba no tuvo la explicaci\u00f3n que merec\u00eda, fue interesante estar presente en esa l\u00ednea de conversi\u00f3n a la radicalizaci\u00f3n.<\/p>\n\n\n\n<p>John Walker, el antagonista y nuevo Capit\u00e1n Am\u00e9rica, con el cual la serie hizo un buen trabajo en transmitirme ese sentimiento de odio hacia \u00e9l, queriendo escupirle en la cara cada que sal\u00eda en la pantalla. Pero esa inestabilidad y apertura a la violencia fue ese deseo inconsciente de ver a Cap escogiendo violencia necesaria en vez de la misericordia distintiva del primer Capit\u00e1n Am\u00e9rica.<\/p>\n\n\n\n<p>En conclusi\u00f3n, seguir\u00e9 esperando que me regrese el buen sabor de boca este junio con el estreno de la serie de nuestro dios n\u00f3rdico favorito, Loki, ya que Bucky y Sam dejaron mucho que desear (no estando peleada con la idea de ver uno que otro episodio en familia de la segunda temporada una tarde de domingo).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ALERTA: CONTIENE SPOILERS Despu\u00e9s de la serie emocionante, enigm\u00e1tica y un tanto rom\u00e1ntica de WandaVision, muchos de nosotros nos quedamos con un buen sabor de boca, con la emoci\u00f3n que&hellip;<\/p>\n","protected":false},"author":5,"featured_media":275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24,22,36],"tags":[35,32,34,33],"class_list":["post-270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-confia-en-mi","category-a-tu-gato","category-series","tag-disney-plus","tag-falcon","tag-marvel","tag-winter-soldier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse &#8211; Lo Siento Mam\u00e1, Falsa Alarma<\/title>\n<meta name=\"description\" content=\"Falcon y el Soldado del Invierno es la gran promesa luego de que Disney+ nos entregara WandaVision. \u00bfEs tan buena?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse &#8211; Lo Siento Mam\u00e1, Falsa Alarma\" \/>\n<meta property=\"og:description\" content=\"Falcon y el Soldado del Invierno es la gran promesa luego de que Disney+ nos entregara WandaVision. \u00bfEs tan buena?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/\" \/>\n<meta property=\"og:site_name\" content=\"Lo Siento Mam\u00e1, Falsa Alarma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bluezonemx-106141254902965\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-27T17:09:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-16T17:01:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/jLXPiKNe6e9mwd76fpGrH3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paula\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BlueZoneMX\" \/>\n<meta name=\"twitter:site\" content=\"@BlueZoneMX\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/\"},\"author\":{\"name\":\"Paula\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#\\\/schema\\\/person\\\/17009cafc252296443115bc66e70344a\"},\"headline\":\"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse\",\"datePublished\":\"2021-04-27T17:09:57+00:00\",\"dateModified\":\"2021-05-16T17:01:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/\"},\"wordCount\":1178,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/jLXPiKNe6e9mwd76fpGrH3.jpeg\",\"keywords\":[\"Disney Plus\",\"Falcon\",\"Marvel\",\"Winter Soldier\"],\"articleSection\":[\"Conf\u00eda en M\u00ed\",\"D\u00edselo a tu Gato\",\"Series\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/\",\"url\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/\",\"name\":\"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse &#8211; Lo Siento Mam\u00e1, Falsa Alarma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/jLXPiKNe6e9mwd76fpGrH3.jpeg\",\"datePublished\":\"2021-04-27T17:09:57+00:00\",\"dateModified\":\"2021-05-16T17:01:09+00:00\",\"description\":\"Falcon y el Soldado del Invierno es la gran promesa luego de que Disney+ nos entregara WandaVision. \u00bfEs tan buena?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/jLXPiKNe6e9mwd76fpGrH3.jpeg\",\"contentUrl\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/jLXPiKNe6e9mwd76fpGrH3.jpeg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/2021\\\/04\\\/27\\\/falcon-soldado-invierno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#website\",\"url\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/\",\"name\":\"Lo Siento Mam\u00e1, Falsa Alarma\",\"description\":\"Un sitio web de noticias sobre todo lo que no sab\u00edas que necesitabas saber: anime, videojuegos, m\u00fasica, cine, series y m\u00e1s.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#organization\",\"name\":\"BlueZone.mx\",\"url\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/CLeRvsec_400x400.jpeg\",\"contentUrl\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/CLeRvsec_400x400.jpeg\",\"width\":400,\"height\":400,\"caption\":\"BlueZone.mx\"},\"image\":{\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Bluezonemx-106141254902965\\\/\",\"https:\\\/\\\/x.com\\\/BlueZoneMX\",\"https:\\\/\\\/www.instagram.com\\\/bluezonemx\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCFzivc1T1IZICf5rfgzeefQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/#\\\/schema\\\/person\\\/17009cafc252296443115bc66e70344a\",\"name\":\"Paula\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35e4be8f0da8f7e2d31805d7abe0f17bed7ced854349c8c1a4de0241e6f998ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35e4be8f0da8f7e2d31805d7abe0f17bed7ced854349c8c1a4de0241e6f998ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35e4be8f0da8f7e2d31805d7abe0f17bed7ced854349c8c1a4de0241e6f998ca?s=96&d=mm&r=g\",\"caption\":\"Paula\"},\"url\":\"https:\\\/\\\/lsmfa.bluezone.mx\\\/index.php\\\/author\\\/paula-bladinieres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse &#8211; Lo Siento Mam\u00e1, Falsa Alarma","description":"Falcon y el Soldado del Invierno es la gran promesa luego de que Disney+ nos entregara WandaVision. \u00bfEs tan buena?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/","og_locale":"es_MX","og_type":"article","og_title":"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse &#8211; Lo Siento Mam\u00e1, Falsa Alarma","og_description":"Falcon y el Soldado del Invierno es la gran promesa luego de que Disney+ nos entregara WandaVision. \u00bfEs tan buena?","og_url":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/","og_site_name":"Lo Siento Mam\u00e1, Falsa Alarma","article_publisher":"https:\/\/www.facebook.com\/Bluezonemx-106141254902965\/","article_published_time":"2021-04-27T17:09:57+00:00","article_modified_time":"2021-05-16T17:01:09+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/jLXPiKNe6e9mwd76fpGrH3.jpeg","type":"image\/jpeg"}],"author":"Paula","twitter_card":"summary_large_image","twitter_creator":"@BlueZoneMX","twitter_site":"@BlueZoneMX","twitter_misc":{"Escrito por":"Paula","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/#article","isPartOf":{"@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/"},"author":{"name":"Paula","@id":"https:\/\/lsmfa.bluezone.mx\/#\/schema\/person\/17009cafc252296443115bc66e70344a"},"headline":"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse","datePublished":"2021-04-27T17:09:57+00:00","dateModified":"2021-05-16T17:01:09+00:00","mainEntityOfPage":{"@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/"},"wordCount":1178,"commentCount":0,"publisher":{"@id":"https:\/\/lsmfa.bluezone.mx\/#organization"},"image":{"@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/#primaryimage"},"thumbnailUrl":"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/jLXPiKNe6e9mwd76fpGrH3.jpeg","keywords":["Disney Plus","Falcon","Marvel","Winter Soldier"],"articleSection":["Conf\u00eda en M\u00ed","D\u00edselo a tu Gato","Series"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/","url":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/","name":"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse &#8211; Lo Siento Mam\u00e1, Falsa Alarma","isPartOf":{"@id":"https:\/\/lsmfa.bluezone.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/#primaryimage"},"image":{"@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/#primaryimage"},"thumbnailUrl":"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/jLXPiKNe6e9mwd76fpGrH3.jpeg","datePublished":"2021-04-27T17:09:57+00:00","dateModified":"2021-05-16T17:01:09+00:00","description":"Falcon y el Soldado del Invierno es la gran promesa luego de que Disney+ nos entregara WandaVision. \u00bfEs tan buena?","breadcrumb":{"@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/#primaryimage","url":"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/jLXPiKNe6e9mwd76fpGrH3.jpeg","contentUrl":"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/jLXPiKNe6e9mwd76fpGrH3.jpeg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/lsmfa.bluezone.mx\/index.php\/2021\/04\/27\/falcon-soldado-invierno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/lsmfa.bluezone.mx\/"},{"@type":"ListItem","position":2,"name":"Falcon, El Soldado del Invierno y el c\u00famulo de complicaciones incomprensibles que trajo Steve Rogers al retirarse"}]},{"@type":"WebSite","@id":"https:\/\/lsmfa.bluezone.mx\/#website","url":"https:\/\/lsmfa.bluezone.mx\/","name":"Lo Siento Mam\u00e1, Falsa Alarma","description":"Un sitio web de noticias sobre todo lo que no sab\u00edas que necesitabas saber: anime, videojuegos, m\u00fasica, cine, series y m\u00e1s.","publisher":{"@id":"https:\/\/lsmfa.bluezone.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lsmfa.bluezone.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lsmfa.bluezone.mx\/#organization","name":"BlueZone.mx","url":"https:\/\/lsmfa.bluezone.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lsmfa.bluezone.mx\/#\/schema\/logo\/image\/","url":"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/CLeRvsec_400x400.jpeg","contentUrl":"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/CLeRvsec_400x400.jpeg","width":400,"height":400,"caption":"BlueZone.mx"},"image":{"@id":"https:\/\/lsmfa.bluezone.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bluezonemx-106141254902965\/","https:\/\/x.com\/BlueZoneMX","https:\/\/www.instagram.com\/bluezonemx\/","https:\/\/www.youtube.com\/channel\/UCFzivc1T1IZICf5rfgzeefQ"]},{"@type":"Person","@id":"https:\/\/lsmfa.bluezone.mx\/#\/schema\/person\/17009cafc252296443115bc66e70344a","name":"Paula","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/35e4be8f0da8f7e2d31805d7abe0f17bed7ced854349c8c1a4de0241e6f998ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35e4be8f0da8f7e2d31805d7abe0f17bed7ced854349c8c1a4de0241e6f998ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35e4be8f0da8f7e2d31805d7abe0f17bed7ced854349c8c1a4de0241e6f998ca?s=96&d=mm&r=g","caption":"Paula"},"url":"https:\/\/lsmfa.bluezone.mx\/index.php\/author\/paula-bladinieres\/"}]}},"jetpack_featured_media_url":"https:\/\/lsmfa.bluezone.mx\/wp-content\/uploads\/2021\/04\/jLXPiKNe6e9mwd76fpGrH3.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/posts\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/comments?post=270"}],"version-history":[{"count":3,"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/posts\/270\/revisions"}],"predecessor-version":[{"id":279,"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/posts\/270\/revisions\/279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/media\/275"}],"wp:attachment":[{"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/media?parent=270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/categories?post=270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lsmfa.bluezone.mx\/index.php\/wp-json\/wp\/v2\/tags?post=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}